{"id":18050,"date":"2026-02-06T14:43:22","date_gmt":"2026-02-06T07:43:22","guid":{"rendered":"https:\/\/www.cmvc.ac.th\/main\/?p=18050"},"modified":"2026-02-06T14:47:13","modified_gmt":"2026-02-06T07:47:13","slug":"%e0%b8%81%e0%b8%a5%e0%b8%b8%e0%b9%88%e0%b8%a1%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%88%e0%b8%b5%e0%b8%99-%e0%b8%aa%e0%b8%b2%e0%b8%82%e0%b8%b2%e0%b8%a7-4","status":"publish","type":"post","link":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/","title":{"rendered":"\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1600\" height=\"1066\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39-1600x1066.jpg\" alt=\"\" class=\"wp-image-18051\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39-1600x1066.jpg 1600w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39-840x560.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39-768x512.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39-1536x1024.jpg 1536w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39-272x182.jpg 272w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39.jpg 2048w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1600\" height=\"1066\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-41-1600x1066.jpg\" alt=\"\" class=\"wp-image-18053\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-41-1600x1066.jpg 1600w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-41-840x560.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-41-768x512.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-41-1536x1024.jpg 1536w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-41-272x182.jpg 272w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-41.jpg 2048w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14<strong><span class=\"has-inline-color has-vivid-red-color\">\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026)<\/span><\/strong> \u0e13 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e42\u0e14\u0e21\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48  \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e30\u0e27\u0e35\u0e27\u0e23\u0e23\u0e13 \u0e27\u0e38\u0e12\u0e34\u0e22\u0e28 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e27\u0e32\u0e2a\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e0a\u0e34\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e08\u0e35\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1600\" height=\"1066\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-9-1600x1066.jpg\" alt=\"\" class=\"wp-image-18052\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-9-1600x1066.jpg 1600w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-9-840x560.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-9-768x512.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-9-1536x1024.jpg 1536w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-9-272x182.jpg 272w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-9.jpg 2048w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1600\" height=\"1066\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-47-1600x1066.jpg\" alt=\"\" class=\"wp-image-18054\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-47-1600x1066.jpg 1600w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-47-840x560.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-47-768x512.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-47-1536x1024.jpg 1536w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-47-272x182.jpg 272w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-47.jpg 2048w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background\" href=\"https:\/\/photos.app.goo.gl\/T6jhKc59YWmr29De8\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e0a\u0e21\u0e20\u0e32\u0e1e\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026)<\/p>\n","protected":false},"author":7,"featured_media":18051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026) - CMVC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026) - CMVC\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/\" \/>\n<meta property=\"og:site_name\" content=\"CMVC\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T07:43:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T07:47:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/\",\"name\":\"CMVC\",\"description\":\"\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#primaryimage\",\"inLanguage\":\"th\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39.jpg\",\"contentUrl\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#webpage\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/\",\"name\":\"\\u0e01\\u0e25\\u0e38\\u0e48\\u0e21\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e20\\u0e32\\u0e29\\u0e32\\u0e08\\u0e35\\u0e19 \\u0e2a\\u0e32\\u0e02\\u0e32\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e20\\u0e32\\u0e29\\u0e32\\u0e41\\u0e25\\u0e30\\u0e01\\u0e32\\u0e23\\u0e08\\u0e31\\u0e14\\u0e01\\u0e32\\u0e23\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e23\\u0e30\\u0e2b\\u0e27\\u0e48\\u0e32\\u0e07\\u0e1b\\u0e23\\u0e30\\u0e40\\u0e17\\u0e28 \\u0e41\\u0e1c\\u0e19\\u0e01\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e01\\u0e32\\u0e23\\u0e08\\u0e31\\u0e14\\u0e01\\u0e32\\u0e23 \\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48 \\u0e08\\u0e31\\u0e14\\u0e01\\u0e34\\u0e08\\u0e01\\u0e23\\u0e23\\u0e21\\u0e27\\u0e31\\u0e19\\u0e15\\u0e23\\u0e38\\u0e29\\u0e08\\u0e35\\u0e19 2569 (Chinese New Year 2026) - CMVC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#primaryimage\"},\"datePublished\":\"2026-02-06T07:43:22+00:00\",\"dateModified\":\"2026-02-06T07:47:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmvc.ac.th\/main\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u0e01\\u0e25\\u0e38\\u0e48\\u0e21\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e20\\u0e32\\u0e29\\u0e32\\u0e08\\u0e35\\u0e19 \\u0e2a\\u0e32\\u0e02\\u0e32\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e20\\u0e32\\u0e29\\u0e32\\u0e41\\u0e25\\u0e30\\u0e01\\u0e32\\u0e23\\u0e08\\u0e31\\u0e14\\u0e01\\u0e32\\u0e23\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e23\\u0e30\\u0e2b\\u0e27\\u0e48\\u0e32\\u0e07\\u0e1b\\u0e23\\u0e30\\u0e40\\u0e17\\u0e28 \\u0e41\\u0e1c\\u0e19\\u0e01\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e01\\u0e32\\u0e23\\u0e08\\u0e31\\u0e14\\u0e01\\u0e32\\u0e23 \\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48 \\u0e08\\u0e31\\u0e14\\u0e01\\u0e34\\u0e08\\u0e01\\u0e23\\u0e23\\u0e21\\u0e27\\u0e31\\u0e19\\u0e15\\u0e23\\u0e38\\u0e29\\u0e08\\u0e35\\u0e19 2569 (Chinese New Year 2026)\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\",\"name\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#personlogo\",\"inLanguage\":\"th\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"caption\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\"},\"url\":\"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026) - CMVC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026) - CMVC","og_description":"\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 6 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026)","og_url":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/","og_site_name":"CMVC","article_published_time":"2026-02-06T07:43:22+00:00","article_modified_time":"2026-02-06T07:47:13+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cmvc.ac.th\/main\/#website","url":"https:\/\/www.cmvc.ac.th\/main\/","name":"CMVC","description":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#primaryimage","inLanguage":"th","url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39.jpg","contentUrl":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2026\/02\/6-2-69-39.jpg","width":2048,"height":1365},{"@type":"WebPage","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#webpage","url":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/","name":"\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026) - CMVC","isPartOf":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#primaryimage"},"datePublished":"2026-02-06T07:43:22+00:00","dateModified":"2026-02-06T07:47:13+00:00","author":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20"},"breadcrumb":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/18050\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmvc.ac.th\/main\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e27\u0e31\u0e19\u0e15\u0e23\u0e38\u0e29\u0e08\u0e35\u0e19 2569 (Chinese New Year 2026)"}]},{"@type":"Person","@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20","name":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","image":{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/#personlogo","inLanguage":"th","url":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","caption":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23"},"url":"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/18050"}],"collection":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/comments?post=18050"}],"version-history":[{"count":4,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/18050\/revisions"}],"predecessor-version":[{"id":18059,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/18050\/revisions\/18059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media\/18051"}],"wp:attachment":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media?parent=18050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/categories?post=18050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/tags?post=18050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}