{"id":14129,"date":"2024-07-12T14:11:03","date_gmt":"2024-07-12T07:11:03","guid":{"rendered":"https:\/\/www.cmvc.ac.th\/main\/?p=14129"},"modified":"2024-07-12T14:11:06","modified_gmt":"2024-07-12T07:11:06","slug":"%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%ad%e0%b8%b2%e0%b8%8a%e0%b8%b5%e0%b8%a7%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%b5-251","status":"publish","type":"post","link":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/","title":{"rendered":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1477\" height=\"1108\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg\" alt=\"\" class=\"wp-image-14130\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg 1477w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n-840x630.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n-320x240.jpg 320w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n-768x576.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n-350x262.jpg 350w\" sizes=\"(max-width: 1477px) 100vw, 1477px\" \/><\/figure>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 12 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e30\u0e27\u0e35\u0e27\u0e23\u0e23\u0e13 \u0e27\u0e38\u0e12\u0e34\u0e22\u0e28 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e0a\u0e19\u0e31\u0e0d\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e42\u0e1b\u0e18\u0e32\u0e21\u0e39\u0e25 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e28\u0e23\u0e35\u0e27\u0e34\u0e44\u0e25 &#8211; \u0e17\u0e2d\u0e07\u0e21\u0e49\u0e27\u0e19 \u0e0a\u0e31\u0e49\u0e19 2 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e2a\u0e21\u0e2a\u0e27\u0e25\u0e35 \u0e04\u0e13\u0e30\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1477\" height=\"1108\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450614384_907053034563643_7963177293127561551_n.jpg\" alt=\"\" class=\"wp-image-14131\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450614384_907053034563643_7963177293127561551_n.jpg 1477w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450614384_907053034563643_7963177293127561551_n-840x630.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450614384_907053034563643_7963177293127561551_n-320x240.jpg 320w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450614384_907053034563643_7963177293127561551_n-768x576.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450614384_907053034563643_7963177293127561551_n-350x262.jpg 350w\" sizes=\"(max-width: 1477px) 100vw, 1477px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 12 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e28\u0e23\u0e35\u0e27\u0e34\u0e44\u0e25 &#8211; \u0e17\u0e2d\u0e07\u0e21\u0e49\u0e27\u0e19 \u0e0a\u0e31\u0e49\u0e19 2 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e2a\u0e21\u0e2a\u0e27\u0e25\u0e35 \u0e04\u0e13\u0e30\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/p>\n","protected":false},"author":7,"featured_media":14130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 - CMVC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 - CMVC\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 12 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e28\u0e23\u0e35\u0e27\u0e34\u0e44\u0e25 - \u0e17\u0e2d\u0e07\u0e21\u0e49\u0e27\u0e19 \u0e0a\u0e31\u0e49\u0e19 2 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e2a\u0e21\u0e2a\u0e27\u0e25\u0e35 \u0e04\u0e13\u0e30\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/\" \/>\n<meta property=\"og:site_name\" content=\"CMVC\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T07:11:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T07:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1477\" \/>\n\t<meta property=\"og:image:height\" content=\"1108\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/\",\"name\":\"CMVC\",\"description\":\"\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#primaryimage\",\"inLanguage\":\"th\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg\",\"contentUrl\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg\",\"width\":1477,\"height\":1108},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#webpage\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/\",\"name\":\"\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48 \\u0e19\\u0e33\\u0e19\\u0e31\\u0e01\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19 \\u0e19\\u0e31\\u0e01\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32 \\u0e40\\u0e02\\u0e49\\u0e32\\u0e23\\u0e48\\u0e27\\u0e21\\u0e1e\\u0e34\\u0e18\\u0e35\\u0e21\\u0e2d\\u0e1a\\u0e17\\u0e38\\u0e19\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e2a\\u0e33\\u0e2b\\u0e23\\u0e31\\u0e1a\\u0e19\\u0e31\\u0e01\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19 \\u0e19\\u0e31\\u0e01\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32 \\u0e42\\u0e04\\u0e23\\u0e07\\u0e01\\u0e32\\u0e23\\u0e1e\\u0e48\\u0e2d\\u0e41\\u0e21\\u0e48\\u0e2d\\u0e38\\u0e1b\\u0e16\\u0e31\\u0e21\\u0e20\\u0e4c \\u0e21\\u0e39\\u0e25\\u0e19\\u0e34\\u0e18\\u0e34\\u0e2b\\u0e21\\u0e2d\\u0e40\\u0e2a\\u0e21 \\u0e1e\\u0e23\\u0e34\\u0e49\\u0e07\\u0e1e\\u0e27\\u0e07\\u0e41\\u0e01\\u0e49\\u0e27 \\u0e1b\\u0e23\\u0e30\\u0e08\\u0e33\\u0e1b\\u0e35\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32 2567 - CMVC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#primaryimage\"},\"datePublished\":\"2024-07-12T07:11:03+00:00\",\"dateModified\":\"2024-07-12T07:11:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmvc.ac.th\/main\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48 \\u0e19\\u0e33\\u0e19\\u0e31\\u0e01\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19 \\u0e19\\u0e31\\u0e01\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32 \\u0e40\\u0e02\\u0e49\\u0e32\\u0e23\\u0e48\\u0e27\\u0e21\\u0e1e\\u0e34\\u0e18\\u0e35\\u0e21\\u0e2d\\u0e1a\\u0e17\\u0e38\\u0e19\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e2a\\u0e33\\u0e2b\\u0e23\\u0e31\\u0e1a\\u0e19\\u0e31\\u0e01\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19 \\u0e19\\u0e31\\u0e01\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32 \\u0e42\\u0e04\\u0e23\\u0e07\\u0e01\\u0e32\\u0e23\\u0e1e\\u0e48\\u0e2d\\u0e41\\u0e21\\u0e48\\u0e2d\\u0e38\\u0e1b\\u0e16\\u0e31\\u0e21\\u0e20\\u0e4c \\u0e21\\u0e39\\u0e25\\u0e19\\u0e34\\u0e18\\u0e34\\u0e2b\\u0e21\\u0e2d\\u0e40\\u0e2a\\u0e21 \\u0e1e\\u0e23\\u0e34\\u0e49\\u0e07\\u0e1e\\u0e27\\u0e07\\u0e41\\u0e01\\u0e49\\u0e27 \\u0e1b\\u0e23\\u0e30\\u0e08\\u0e33\\u0e1b\\u0e35\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32 2567\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\",\"name\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#personlogo\",\"inLanguage\":\"th\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"caption\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\"},\"url\":\"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 - CMVC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 - CMVC","og_description":"\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 12 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2567 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 \u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e28\u0e23\u0e35\u0e27\u0e34\u0e44\u0e25 - \u0e17\u0e2d\u0e07\u0e21\u0e49\u0e27\u0e19 \u0e0a\u0e31\u0e49\u0e19 2 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e2a\u0e21\u0e2a\u0e27\u0e25\u0e35 \u0e04\u0e13\u0e30\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","og_url":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/","og_site_name":"CMVC","article_published_time":"2024-07-12T07:11:03+00:00","article_modified_time":"2024-07-12T07:11:06+00:00","og_image":[{"width":1477,"height":1108,"url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cmvc.ac.th\/main\/#website","url":"https:\/\/www.cmvc.ac.th\/main\/","name":"CMVC","description":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#primaryimage","inLanguage":"th","url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg","contentUrl":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/07\/450736089_907053084563638_6920063393627488264_n.jpg","width":1477,"height":1108},{"@type":"WebPage","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#webpage","url":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/","name":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567 - CMVC","isPartOf":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#primaryimage"},"datePublished":"2024-07-12T07:11:03+00:00","dateModified":"2024-07-12T07:11:06+00:00","author":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20"},"breadcrumb":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/14129\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmvc.ac.th\/main\/"},{"@type":"ListItem","position":2,"name":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e07\u0e1e\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2567"}]},{"@type":"Person","@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20","name":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","image":{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/#personlogo","inLanguage":"th","url":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","caption":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23"},"url":"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/14129"}],"collection":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/comments?post=14129"}],"version-history":[{"count":1,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/14129\/revisions"}],"predecessor-version":[{"id":14132,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/14129\/revisions\/14132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media\/14130"}],"wp:attachment":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media?parent=14129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/categories?post=14129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/tags?post=14129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}