{"id":11191,"date":"2022-12-02T14:46:04","date_gmt":"2022-12-02T07:46:04","guid":{"rendered":"https:\/\/www.cmvc.ac.th\/main\/?p=11191"},"modified":"2022-12-02T18:12:11","modified_gmt":"2022-12-02T11:12:11","slug":"%e0%b8%9e%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%97%e0%b8%b3%e0%b8%9a%e0%b8%b8%e0%b8%8d%e0%b8%95%e0%b8%b1%e0%b8%81%e0%b8%9a%e0%b8%b2%e0%b8%95%e0%b8%a3-%e0%b9%80%e0%b8%9e%e0%b8%b7%e0%b9%88%e0%b8%ad-2","status":"publish","type":"post","link":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/","title":{"rendered":"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1367\" height=\"912\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0039.jpg\" alt=\"\" class=\"wp-image-11194\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0039.jpg 1367w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0039-840x560.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0039-768x512.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0039-272x182.jpg 272w\" sizes=\"(max-width: 1367px) 100vw, 1367px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1600\" height=\"1068\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0176-1600x1068.jpg\" alt=\"\" class=\"wp-image-11196\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0176-1600x1068.jpg 1600w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0176-840x560.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0176-768x512.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0176-1536x1025.jpg 1536w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0176-2048x1367.jpg 2048w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0176-272x182.jpg 272w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 2 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e19\u0e32\u0e22\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e19\u0e32\u0e2b\u0e25\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e23\u0e39 \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e2a\u0e21\u0e20\u0e1e (5 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21) \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e21\u0e35\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e14.\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e2b\u0e32\u0e23 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1452\" height=\"969\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg\" alt=\"\" class=\"wp-image-11192\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg 1452w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172-840x561.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172-768x513.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172-272x182.jpg 272w\" sizes=\"(max-width: 1452px) 100vw, 1452px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1600\" height=\"1068\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0213-1600x1068.jpg\" alt=\"\" class=\"wp-image-11195\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0213-1600x1068.jpg 1600w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0213-840x560.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0213-768x512.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0213-1536x1025.jpg 1536w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0213-2048x1367.jpg 2048w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0213-272x182.jpg 272w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link has-black-color has-luminous-vivid-amber-background-color has-text-color has-background\" href=\"https:\/\/photos.app.goo.gl\/j5v774g1aruWMojU6\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e0a\u0e21\u0e20\u0e32\u0e1e\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 2 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e2a\u0e21\u0e20\u0e1e (5 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21) \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22<\/p>\n","protected":false},"author":7,"featured_media":11192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 - CMVC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 - CMVC\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 2 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e2a\u0e21\u0e20\u0e1e (5 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21) \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/\" \/>\n<meta property=\"og:site_name\" content=\"CMVC\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-02T07:46:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-02T11:12:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1452\" \/>\n\t<meta property=\"og:image:height\" content=\"969\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/\",\"name\":\"CMVC\",\"description\":\"\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#primaryimage\",\"inLanguage\":\"th\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg\",\"contentUrl\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg\",\"width\":1452,\"height\":969},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#webpage\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/\",\"name\":\"\\u0e1e\\u0e34\\u0e18\\u0e35\\u0e17\\u0e33\\u0e1a\\u0e38\\u0e0d\\u0e15\\u0e31\\u0e01\\u0e1a\\u0e32\\u0e15\\u0e23 \\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2d\\u0e38\\u0e17\\u0e34\\u0e28\\u0e40\\u0e1b\\u0e47\\u0e19\\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e0a\\u0e01\\u0e38\\u0e28\\u0e25\\u0e41\\u0e14\\u0e48\\u0e1e\\u0e23\\u0e30\\u0e1a\\u0e32\\u0e17\\u0e2a\\u0e21\\u0e40\\u0e14\\u0e47\\u0e08\\u0e1e\\u0e23\\u0e30\\u0e1a\\u0e23\\u0e21\\u0e0a\\u0e19\\u0e01\\u0e32\\u0e18\\u0e34\\u0e40\\u0e1a\\u0e28\\u0e23 \\u0e21\\u0e2b\\u0e32\\u0e20\\u0e39\\u0e21\\u0e34\\u0e1e\\u0e25\\u0e2d\\u0e14\\u0e38\\u0e25\\u0e22\\u0e40\\u0e14\\u0e0a\\u0e21\\u0e2b\\u0e32\\u0e23\\u0e32\\u0e0a \\u0e1a\\u0e23\\u0e21\\u0e19\\u0e32\\u0e16\\u0e1a\\u0e1e\\u0e34\\u0e15\\u0e23 \\u0e23\\u0e31\\u0e0a\\u0e01\\u0e32\\u0e25\\u0e17\\u0e35\\u0e48 9 - CMVC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#primaryimage\"},\"datePublished\":\"2022-12-02T07:46:04+00:00\",\"dateModified\":\"2022-12-02T11:12:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmvc.ac.th\/main\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u0e1e\\u0e34\\u0e18\\u0e35\\u0e17\\u0e33\\u0e1a\\u0e38\\u0e0d\\u0e15\\u0e31\\u0e01\\u0e1a\\u0e32\\u0e15\\u0e23 \\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2d\\u0e38\\u0e17\\u0e34\\u0e28\\u0e40\\u0e1b\\u0e47\\u0e19\\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e0a\\u0e01\\u0e38\\u0e28\\u0e25\\u0e41\\u0e14\\u0e48\\u0e1e\\u0e23\\u0e30\\u0e1a\\u0e32\\u0e17\\u0e2a\\u0e21\\u0e40\\u0e14\\u0e47\\u0e08\\u0e1e\\u0e23\\u0e30\\u0e1a\\u0e23\\u0e21\\u0e0a\\u0e19\\u0e01\\u0e32\\u0e18\\u0e34\\u0e40\\u0e1a\\u0e28\\u0e23 \\u0e21\\u0e2b\\u0e32\\u0e20\\u0e39\\u0e21\\u0e34\\u0e1e\\u0e25\\u0e2d\\u0e14\\u0e38\\u0e25\\u0e22\\u0e40\\u0e14\\u0e0a\\u0e21\\u0e2b\\u0e32\\u0e23\\u0e32\\u0e0a \\u0e1a\\u0e23\\u0e21\\u0e19\\u0e32\\u0e16\\u0e1a\\u0e1e\\u0e34\\u0e15\\u0e23 \\u0e23\\u0e31\\u0e0a\\u0e01\\u0e32\\u0e25\\u0e17\\u0e35\\u0e48 9\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\",\"name\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#personlogo\",\"inLanguage\":\"th\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"caption\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\"},\"url\":\"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 - CMVC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 - CMVC","og_description":"\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 2 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2565 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e2a\u0e21\u0e20\u0e1e (5 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21) \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22","og_url":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/","og_site_name":"CMVC","article_published_time":"2022-12-02T07:46:04+00:00","article_modified_time":"2022-12-02T11:12:11+00:00","og_image":[{"width":1452,"height":969,"url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cmvc.ac.th\/main\/#website","url":"https:\/\/www.cmvc.ac.th\/main\/","name":"CMVC","description":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#primaryimage","inLanguage":"th","url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg","contentUrl":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/12\/DSC_0172.jpg","width":1452,"height":969},{"@type":"WebPage","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#webpage","url":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/","name":"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9 - CMVC","isPartOf":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#primaryimage"},"datePublished":"2022-12-02T07:46:04+00:00","dateModified":"2022-12-02T11:12:11+00:00","author":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20"},"breadcrumb":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/information\/11191\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmvc.ac.th\/main\/"},{"@type":"ListItem","position":2,"name":"\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e38\u0e28\u0e25\u0e41\u0e14\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e21\u0e2b\u0e32\u0e20\u0e39\u0e21\u0e34\u0e1e\u0e25\u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e1a\u0e23\u0e21\u0e19\u0e32\u0e16\u0e1a\u0e1e\u0e34\u0e15\u0e23 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 9"}]},{"@type":"Person","@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20","name":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","image":{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/#personlogo","inLanguage":"th","url":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","caption":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23"},"url":"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/11191"}],"collection":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/comments?post=11191"}],"version-history":[{"count":4,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/11191\/revisions"}],"predecessor-version":[{"id":11201,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/11191\/revisions\/11201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media\/11192"}],"wp:attachment":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media?parent=11191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/categories?post=11191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/tags?post=11191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}