{"id":10975,"date":"2022-11-01T11:25:44","date_gmt":"2022-11-01T04:25:44","guid":{"rendered":"https:\/\/www.cmvc.ac.th\/main\/?p=10975"},"modified":"2022-11-01T11:25:46","modified_gmt":"2022-11-01T04:25:46","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b2%e0%b8%9e%e0%b8%b4%e0%b8%88%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%a3%e0%b9%88%e0%b8%b2-20","status":"publish","type":"post","link":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1600\" height=\"900\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65-1600x900.jpg\" alt=\"\" class=\"wp-image-10974\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65-1600x900.jpg 1600w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65-840x473.jpg 840w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65-768x432.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65-1536x864.jpg 1536w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65.jpg 1920w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img class=\"wpdm_icon\" alt=\"Icon\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.cmvc.ac.th\/main\/download\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b2%e0%b8%9e%e0%b8%b4%e0%b8%88%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%a3%e0%b9%88%e0%b8%b2-20\/'>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 file(s) <i class=\"fas fa-hdd ml-3\"><\/i> 1.17 MB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.cmvc.ac.th\/main\/download\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b2%e0%b8%9e%e0%b8%b4%e0%b8%88%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%a3%e0%b9%88%e0%b8%b2-20\/?wpdmdl=10973&refresh=6a04dc0a071621778703370\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07<\/p>\n","protected":false},"author":7,"featured_media":10974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 - CMVC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 - CMVC\" \/>\n<meta property=\"og:description\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/\" \/>\n<meta property=\"og:site_name\" content=\"CMVC\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-01T04:25:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-01T04:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/\",\"name\":\"CMVC\",\"description\":\"\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#primaryimage\",\"inLanguage\":\"th\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65.jpg\",\"contentUrl\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#webpage\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/\",\"name\":\"\\u0e1b\\u0e23\\u0e30\\u0e01\\u0e32\\u0e28\\u0e1b\\u0e23\\u0e30\\u0e0a\\u0e32\\u0e1e\\u0e34\\u0e08\\u0e32\\u0e23\\u0e13\\u0e4c(\\u0e23\\u0e48\\u0e32\\u0e07) \\u0e23\\u0e32\\u0e22\\u0e25\\u0e30\\u0e40\\u0e2d\\u0e35\\u0e22\\u0e14\\u0e04\\u0e38\\u0e13\\u0e25\\u0e31\\u0e01\\u0e29\\u0e13\\u0e30\\u0e40\\u0e09\\u0e1e\\u0e32\\u0e30\\u0e04\\u0e23\\u0e38\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\\u0e40\\u0e04\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07 Interactive Presenter \\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e15\\u0e34\\u0e14\\u0e15\\u0e31\\u0e49\\u0e07 - CMVC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#primaryimage\"},\"datePublished\":\"2022-11-01T04:25:44+00:00\",\"dateModified\":\"2022-11-01T04:25:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmvc.ac.th\/main\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u0e1b\\u0e23\\u0e30\\u0e01\\u0e32\\u0e28\\u0e1b\\u0e23\\u0e30\\u0e0a\\u0e32\\u0e1e\\u0e34\\u0e08\\u0e32\\u0e23\\u0e13\\u0e4c(\\u0e23\\u0e48\\u0e32\\u0e07) \\u0e23\\u0e32\\u0e22\\u0e25\\u0e30\\u0e40\\u0e2d\\u0e35\\u0e22\\u0e14\\u0e04\\u0e38\\u0e13\\u0e25\\u0e31\\u0e01\\u0e29\\u0e13\\u0e30\\u0e40\\u0e09\\u0e1e\\u0e32\\u0e30\\u0e04\\u0e23\\u0e38\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\\u0e40\\u0e04\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07 Interactive Presenter \\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e15\\u0e34\\u0e14\\u0e15\\u0e31\\u0e49\\u0e07\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20\",\"name\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#personlogo\",\"inLanguage\":\"th\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g\",\"caption\":\"\\u0e20\\u0e31\\u0e2a\\u0e23\\u0e32\\u0e20\\u0e23\\u0e13\\u0e4c \\u0e2a\\u0e38\\u0e02\\u0e2d\\u0e31\\u0e21\\u0e1e\\u0e23\"},\"url\":\"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 - CMVC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 - CMVC","og_description":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07","og_url":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/","og_site_name":"CMVC","article_published_time":"2022-11-01T04:25:44+00:00","article_modified_time":"2022-11-01T04:25:46+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cmvc.ac.th\/main\/#website","url":"https:\/\/www.cmvc.ac.th\/main\/","name":"CMVC","description":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#primaryimage","inLanguage":"th","url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65.jpg","contentUrl":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/11\/1-11-65.jpg","width":1920,"height":1080},{"@type":"WebPage","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#webpage","url":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/","name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 - CMVC","isPartOf":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#primaryimage"},"datePublished":"2022-11-01T04:25:44+00:00","dateModified":"2022-11-01T04:25:46+00:00","author":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20"},"breadcrumb":{"@id":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmvc.ac.th\/main\/news\/supplies\/10975\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmvc.ac.th\/main\/"},{"@type":"ListItem","position":2,"name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e4c(\u0e23\u0e48\u0e32\u0e07) \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 Interactive Presenter \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07"}]},{"@type":"Person","@id":"https:\/\/www.cmvc.ac.th\/main\/#\/schema\/person\/e1dd1bc40a4d1ff630c378478ebdbf20","name":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23","image":{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/#personlogo","inLanguage":"th","url":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a1cc39dda571e6a1de1a27b26f79a1a?s=96&d=mm&r=g","caption":"\u0e20\u0e31\u0e2a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e2a\u0e38\u0e02\u0e2d\u0e31\u0e21\u0e1e\u0e23"},"url":"https:\/\/www.cmvc.ac.th\/main\/author\/passaraporn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/10975"}],"collection":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/comments?post=10975"}],"version-history":[{"count":1,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/10975\/revisions"}],"predecessor-version":[{"id":10976,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/posts\/10975\/revisions\/10976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media\/10974"}],"wp:attachment":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media?parent=10975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/categories?post=10975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/tags?post=10975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}