{"id":2555,"date":"2020-10-07T19:22:04","date_gmt":"2020-10-07T12:22:04","guid":{"rendered":"https:\/\/www.cmvc.ac.th\/main\/?page_id=2555"},"modified":"2025-06-09T13:29:57","modified_gmt":"2025-06-09T06:29:57","slug":"rbm","status":"publish","type":"page","link":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/","title":{"rendered":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01"},"content":{"rendered":"<div id=\"pl-2555\"  class=\"panel-layout\" ><div id=\"pg-2555-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-2555-0\" data-stretch-type=\"full\" ><div id=\"pgc-2555-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-0-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"panel-widget-style panel-widget-style-for-2555-0-0-0\" ><div class=\"so-widget-sow-headline so-widget-sow-headline-default-59d89934d673\"><div class=\"sow-headline-container \">\n\t<h1 class='sow-headline'>\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<\/h1><h3 class='sow-sub-headline'>Retail Business Management Program<\/h3><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-2555-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2555-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-1-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"so-widget-sow-headline so-widget-sow-headline-default-aaa639850946\"><div class=\"sow-headline-container \">\n\t<h1 class='sow-headline'>\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e19\u0e35\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (\u0e1b\u0e27\u0e2a.) \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e27\u0e34\u0e20\u0e32\u0e04\u0e35<\/h1><h3 class='sow-sub-headline'>\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e08\u0e1a \u0e1b\u0e27\u0e0a. \u0e2b\u0e23\u0e37\u0e2d \u0e21.6 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32<\/h3><\/div><\/div><\/div><\/div><\/div><div id=\"pg-2555-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2555-2-0\"  class=\"panel-grid-cell\" ><div data-siteorigin-parallax=\"{&quot;backgroundUrl&quot;:&quot;https:\\\/\\\/www.cmvc.ac.th\\\/main\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/background-img-program-parallax.jpg&quot;,&quot;backgroundSize&quot;:[500,600],&quot;backgroundSizing&quot;:&quot;original&quot;,&quot;limitMotion&quot;:&quot;auto&quot;}\" class=\"panel-cell-style panel-cell-style-for-2555-2-0\" ><div id=\"panel-2555-2-0-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"2\" ><img width=\"400\" height=\"500\" src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2020\/10\/img-hvc-retail-management.png\" class=\"image wp-image-2366  attachment-full size-full\" alt=\"\" loading=\"lazy\" style=\"max-width: 100%; height: auto;\" \/><\/div><\/div><\/div><div id=\"pgc-2555-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-2-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"3\" >\t\t\t<div class=\"textwidget\"><h3>\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19<\/h3>\n<ul>\n<li>\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e2b\u0e25\u0e31\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li>\n<li>\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 \/ \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49 \/ \u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21<\/li>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e04\u0e33\u0e19\u0e36\u0e07\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/li>\n<li>\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e<\/li>\n<li>\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e<\/li>\n<li>\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08<\/li>\n<li>\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e02\u0e32\u0e22<\/li>\n<li>\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<\/li>\n<li>\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e20\u0e32\u0e27\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25<\/li>\n<li>\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<\/li>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c<\/li>\n<\/ul>\n<h3>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e0a\u0e35\u0e1e<\/h3>\n<p>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1d\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e19\u0e01\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e30\u0e02\u0e19\u0e32\u0e14\u0e22\u0e48\u0e2d\u0e21 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e07\u0e04\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<\/p>\n<h3>\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 (\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19)<\/h3>\n<ul>\n<li><strong>\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10<\/strong>\u00a08,000 &#8211; 15,000 \u0e1a\u0e32\u0e17<\/li>\n<li><strong>\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19<\/strong>\u00a09,000 &#8211; 18,000 \u0e1a\u0e32\u0e17<\/li>\n<li><strong>\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e2d\u0e34\u0e2a\u0e23\u0e30<\/strong>\u00a0\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c<\/li>\n<\/ul>\n<h3>\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d<\/h3>\n<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35\u0e44\u0e14\u0e49 (2 \u0e1b\u0e35 \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07)<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-2555-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2555-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-3-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"so-widget-sow-headline so-widget-sow-headline-default-55294cad2c21\"><div class=\"sow-headline-container \">\n\t<h1 class='sow-headline'>\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19<\/h1><h3 class='sow-sub-headline'>Teachers<\/h3>\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div id=\"pg-2555-4\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-2555-4\" data-stretch-type=\"full\" ><div id=\"pgc-2555-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-4-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"5\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-17bc2272b535\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21-\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35-700x840.jpg\" width=\"700\" height=\"840\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21-\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35-700x840.jpg 700w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21-\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35-768x922.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21-\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35-42x50.jpg 42w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21-\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35-83x100.jpg 83w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21-\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35.jpg 900w\" sizes=\"(max-width: 700px) 100vw, 700px\" title=\"\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-2555-4-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-4-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"6\" >\t\t\t<div class=\"textwidget\"><h3 style=\"margin: 0 0 5px;\">\u0e19\u0e32\u0e22\u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e18\u0e23\u0e23\u0e21\u00a0 \u0e40\u0e15\u0e0a\u0e30\u0e15\u0e32\u0e21\u0e35<\/h3>\n<p>\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<br \/>\n\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39<\/p>\n<p><i class=\"si-mail\"><\/i> example@mail.com<br \/>\n<i class=\"si-mobile\"><\/i> 08 8888 8888<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2555-4-2\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-4-2-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"7\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-17bc2272b535\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c-\u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27-700x840.jpg\" width=\"700\" height=\"840\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c-\u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27-700x840.jpg 700w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c-\u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27-768x922.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c-\u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27-42x50.jpg 42w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c-\u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27-83x100.jpg 83w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c-\u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27.jpg 900w\" sizes=\"(max-width: 700px) 100vw, 700px\" title=\"\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c \u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-2555-4-3\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-4-3-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"8\" >\t\t\t<div class=\"textwidget\"><h3 style=\"margin: 0 0 5px;\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e38\u0e20\u0e23\u0e25\u0e31\u0e04\u0e19\u0e4c \u0e19\u0e19\u0e17\u0e4c\u0e41\u0e01\u0e49\u0e27<\/h3>\n<p>\u0e04\u0e23\u0e39\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<br \/>\n\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39<\/p>\n<p><i class=\"si-mail\"><\/i> example@mail.com<br \/>\n<i class=\"si-mobile\"><\/i> 08 8888 8888<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-2555-5\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-2555-5\" data-stretch-type=\"full\" ><div id=\"pgc-2555-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-5-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"9\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-17bc2272b535\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/01\/\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23-694x840.jpg\" width=\"694\" height=\"840\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/01\/\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23-694x840.jpg 694w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/01\/\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23-1322x1600.jpg 1322w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/01\/\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23-768x930.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/01\/\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23-1269x1536.jpg 1269w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/01\/\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23.jpg 1652w\" sizes=\"(max-width: 694px) 100vw, 694px\" title=\"\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-2555-5-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-5-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"10\" >\t\t\t<div class=\"textwidget\"><h3 style=\"margin: 0 0 5px;\">\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e34\u0e28\u0e23\u0e4c\u0e01\u0e23\u00a0 \u0e04\u0e25\u0e48\u0e2d\u0e07\u0e41\u0e04\u0e25\u0e48\u0e27<\/h3>\n<p>\u0e04\u0e23\u0e39\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<br \/>\n\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39<\/p>\n<p><i class=\"si-mail\"><\/i> example@mail.com<br \/>\n<i class=\"si-mobile\"><\/i> 08 8888 8888<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2555-5-2\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-5-2-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"11\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-17bc2272b535\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/03\/\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32-694x840.png\" width=\"694\" height=\"840\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/03\/\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32-694x840.png 694w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/03\/\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32-1322x1600.png 1322w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/03\/\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32-768x930.png 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/03\/\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32-1269x1536.png 1269w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2025\/03\/\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32.png 1652w\" sizes=\"(max-width: 694px) 100vw, 694px\" title=\"\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-2555-5-3\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-5-3-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"12\" >\t\t\t<div class=\"textwidget\"><h3 style=\"margin: 0 0 5px;\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23\u0e23\u0e13\u0e32 \u0e1e\u0e23\u0e2b\u0e21\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c<\/h3>\n<p>\u0e04\u0e23\u0e39\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<br \/>\n\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39<\/p>\n<p><i class=\"si-mail\"><\/i> example@mail.com<br \/>\n<i class=\"si-mobile\"><\/i> 08 8888 8888<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-2555-6\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-2555-6\" data-stretch-type=\"full\" ><div id=\"pgc-2555-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-6-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"13\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-17bc2272b535\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c-\u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c-700x840.jpg\" width=\"700\" height=\"840\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c-\u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c-700x840.jpg 700w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c-\u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c-768x922.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c-\u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c-42x50.jpg 42w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c-\u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c-83x100.jpg 83w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2022\/05\/\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c-\u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c.jpg 900w\" sizes=\"(max-width: 700px) 100vw, 700px\" title=\"\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c \u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-2555-6-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-6-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"14\" >\t\t\t<div class=\"textwidget\"><h3 style=\"margin: 0 0 5px;\">\u0e19\u0e32\u0e22\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e28\u0e4c \u0e40\u0e25\u0e02\u0e30\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c<\/h3>\n<p>\u0e04\u0e23\u0e39\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<br \/>\n\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23<\/p>\n<p><i class=\"si-mail\"><\/i> example@mail.com<br \/>\n<i class=\"si-mobile\"><\/i> 08 8888 8888<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2555-6-2\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-6-2-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"15\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-17bc2272b535\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c-\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23-613x840.jpg\" width=\"613\" height=\"840\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c-\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23-613x840.jpg 613w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c-\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23-1168x1600.jpg 1168w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c-\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23-768x1052.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c-\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23-1121x1536.jpg 1121w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c-\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23.jpg 1460w\" sizes=\"(max-width: 613px) 100vw, 613px\" title=\"\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-2555-6-3\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-6-3-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"16\" >\t\t\t<div class=\"textwidget\"><h3 style=\"margin: 0 0 5px;\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e01\u0e31\u0e25\u0e22\u0e23\u0e31\u0e15\u0e19\u0e4c\u00a0 \u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32\u0e25\u0e31\u0e07\u0e01\u0e23<\/h3>\n<p>\u0e04\u0e23\u0e39\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<br \/>\n\u0e04\u0e23\u0e39\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e2d\u0e19<\/p>\n<p><i class=\"si-mail\"><\/i> example@mail.com<br \/>\n<i class=\"si-mobile\"><\/i> 08 8888 8888<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-2555-7\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-2555-7\" data-stretch-type=\"full\" ><div id=\"pgc-2555-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-7-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"17\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-17bc2272b535\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e1a\u0e38\u0e29\u0e23\u0e32\u0e04\u0e31\u0e21-\u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d-613x840.jpg\" width=\"613\" height=\"840\" srcset=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e1a\u0e38\u0e29\u0e23\u0e32\u0e04\u0e31\u0e21-\u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d-613x840.jpg 613w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e1a\u0e38\u0e29\u0e23\u0e32\u0e04\u0e31\u0e21-\u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d-1168x1600.jpg 1168w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e1a\u0e38\u0e29\u0e23\u0e32\u0e04\u0e31\u0e21-\u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d-768x1052.jpg 768w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e1a\u0e38\u0e29\u0e23\u0e32\u0e04\u0e31\u0e21-\u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d-1121x1536.jpg 1121w, https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2024\/06\/\u0e1a\u0e38\u0e29\u0e23\u0e32\u0e04\u0e31\u0e21-\u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d.jpg 1460w\" sizes=\"(max-width: 613px) 100vw, 613px\" title=\"\u0e1a\u0e38\u0e29\u0e23\u0e32\u0e04\u0e31\u0e21 \u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-2555-7-1\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-7-1-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"18\" >\t\t\t<div class=\"textwidget\"><h3 style=\"margin: 0 0 5px;\">\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1a\u0e38\u0e28\u0e23\u0e32\u0e04\u0e31\u0e21\u00a0 \u0e40\u0e2a\u0e21\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d<\/h3>\n<p>\u0e04\u0e23\u0e39\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01<br \/>\n\u0e04\u0e23\u0e39\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e2d\u0e19<\/p>\n<p><i class=\"si-mail\"><\/i> example@mail.com<br \/>\n<i class=\"si-mobile\"><\/i> 08 8888 8888<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-2555-7-2\"  class=\"panel-grid-cell panel-grid-cell-empty panel-grid-cell-mobile-last\" ><\/div><div id=\"pgc-2555-7-3\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><div id=\"pg-2555-8\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-2555-8-0\"  class=\"panel-grid-cell\" ><div id=\"panel-2555-8-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"19\" >\t\t\t<div class=\"textwidget\"><h3>\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a<\/h3>\n<ol>\n<li>\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e2d\u0e19 \u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e2d\u0e19\u0e23\u0e27\u0e21\u0e41\u0e25\u0e30\u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32<\/li>\n<li>\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e14\u0e39\u0e41\u0e25 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e01\u0e33\u0e01\u0e31\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e43\u0e19\u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e25\u0e30\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e41\u0e1a\u0e1a\u0e41\u0e1c\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23<\/li>\n<li>\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e44\u0e14\u0e49<\/li>\n<li>\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e01\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19<\/li>\n<li>\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e15\u0e33\u0e23\u0e32 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e2d\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46<\/li>\n<li>\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e04\u0e23\u0e39 \u0e43\u0e1a\u0e07\u0e32\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e41\u0e1f\u0e49\u0e21\u0e2a\u0e30\u0e2a\u0e21\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19<\/li>\n<li>\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e43\u0e1a\u0e07\u0e32\u0e19<\/li>\n<li>\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d<\/li>\n<li>\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e43\u0e19\u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e41\u0e1a\u0e1a\u0e41\u0e1c\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e19\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e43\u0e19\u0e41\u0e1c\u0e19\u0e01\u0e27\u0e34\u0e0a\u0e32<\/li>\n<li>\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32<\/li>\n<li>\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e40\u0e2a\u0e19\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e02\u0e31\u0e49\u0e19<\/li>\n<li>\u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22<\/li>\n<li>\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22<\/li>\n<\/ol>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01Retail Business Managemen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2556,"parent":746,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 - CMVC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 - CMVC\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01Retail Business Managemen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/\" \/>\n<meta property=\"og:site_name\" content=\"CMVC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T06:29:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2020\/10\/main-banner-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/\",\"name\":\"CMVC\",\"description\":\"\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e2d\\u0e32\\u0e0a\\u0e35\\u0e27\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e0a\\u0e35\\u0e22\\u0e07\\u0e43\\u0e2b\\u0e21\\u0e48\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#primaryimage\",\"inLanguage\":\"th\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2020\/10\/main-banner-10.jpg\",\"contentUrl\":\"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2020\/10\/main-banner-10.jpg\",\"width\":1200,\"height\":500},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#webpage\",\"url\":\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/\",\"name\":\"\\u0e2a\\u0e32\\u0e02\\u0e32\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e01\\u0e32\\u0e23\\u0e08\\u0e31\\u0e14\\u0e01\\u0e32\\u0e23\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e04\\u0e49\\u0e32\\u0e1b\\u0e25\\u0e35\\u0e01 - CMVC\",\"isPartOf\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#primaryimage\"},\"datePublished\":\"2020-10-07T12:22:04+00:00\",\"dateModified\":\"2025-06-09T06:29:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cmvc.ac.th\/main\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u0e2a\\u0e32\\u0e02\\u0e32\\u0e27\\u0e34\\u0e0a\\u0e32\",\"item\":\"https:\/\/www.cmvc.ac.th\/main\/programs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\\u0e2a\\u0e32\\u0e02\\u0e32\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e01\\u0e32\\u0e23\\u0e08\\u0e31\\u0e14\\u0e01\\u0e32\\u0e23\\u0e18\\u0e38\\u0e23\\u0e01\\u0e34\\u0e08\\u0e04\\u0e49\\u0e32\\u0e1b\\u0e25\\u0e35\\u0e01\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 - CMVC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 - CMVC","og_description":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01Retail Business Managemen [&hellip;]","og_url":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/","og_site_name":"CMVC","article_modified_time":"2025-06-09T06:29:57+00:00","og_image":[{"width":1200,"height":500,"url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2020\/10\/main-banner-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.cmvc.ac.th\/main\/#website","url":"https:\/\/www.cmvc.ac.th\/main\/","name":"CMVC","description":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmvc.ac.th\/main\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","@id":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#primaryimage","inLanguage":"th","url":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2020\/10\/main-banner-10.jpg","contentUrl":"https:\/\/www.cmvc.ac.th\/main\/wp-content\/uploads\/2020\/10\/main-banner-10.jpg","width":1200,"height":500},{"@type":"WebPage","@id":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#webpage","url":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/","name":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 - CMVC","isPartOf":{"@id":"https:\/\/www.cmvc.ac.th\/main\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#primaryimage"},"datePublished":"2020-10-07T12:22:04+00:00","dateModified":"2025-06-09T06:29:57+00:00","breadcrumb":{"@id":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmvc.ac.th\/main\/programs\/rbm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cmvc.ac.th\/main\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32","item":"https:\/\/www.cmvc.ac.th\/main\/programs\/"},{"@type":"ListItem","position":3,"name":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01"}]}]}},"_links":{"self":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/pages\/2555"}],"collection":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/comments?post=2555"}],"version-history":[{"count":7,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/pages\/2555\/revisions"}],"predecessor-version":[{"id":16168,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/pages\/2555\/revisions\/16168"}],"up":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/pages\/746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media\/2556"}],"wp:attachment":[{"href":"https:\/\/www.cmvc.ac.th\/main\/wp-json\/wp\/v2\/media?parent=2555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}